{"id":43251,"date":"2017-02-05T16:41:21","date_gmt":"2017-02-05T08:41:21","guid":{"rendered":"http:\/\/www.paudimodel.com\/?p=43251"},"modified":"2017-04-16T22:48:14","modified_gmt":"2017-04-16T14:48:14","slug":"2017-international-toyfair-nuremberg-february-1-6th","status":"publish","type":"post","link":"https:\/\/www.paudimodel.com\/de\/2017-international-toyfair-nuremberg-february-1-6th\/","title":{"rendered":"Internationale Spielwarenmesse 2017 in N\u00fcrnberg \u2013 1. bis 6. Februar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-48805\" src=\"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg\" alt=\"toys-2\" width=\"1024\" height=\"724\" \/><\/p>\n<p>MC-Modell<br \/>\nUniverselle Hobbys<br \/>\nMinichamps<br \/>\nParagon<br \/>\nAUTOart\/Gateway<br \/>\nOttOmobile<br \/>\nFunke<br \/>\nBilden<br \/>\nGummistiefel<br \/>\nNorev<br \/>\nSunrich<br \/>\nDie Druckgussgesellschaft<br \/>\nNZG Modelle<br \/>\nMaisto\/Bbruago<\/p>","protected":false},"excerpt":{"rendered":"<p>MC Model Universal Hobbies Minichamps Paragon AUTOart\/Gateway OttOmobile Spark Make UP Welly Norev Sunrich The Diecast Company NZG Modelle Maisto\/Bbruago<\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[486,474,488,473,489],"class_list":["post-43251","post","type-post","status-publish","format-standard","hentry","category-blog","tag-118-die-cast-model-car","tag-car-model","tag-international-toyfair","tag-model-car","tag-toyfair"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>2017 International ToyFair in Nuremberg - February 1 - 6th - Paudi Model | High Quality Diecast Model<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paudimodel.com\/de\/2017-international-toyfair-nuremberg-february-1-6th\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2017 International ToyFair in Nuremberg - February 1 - 6th\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paudimodel.com\/de\/2017-international-toyfair-nuremberg-february-1-6th\/\" \/>\n<meta property=\"og:site_name\" content=\"Paudi Model | High Quality Diecast Model\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook\/paudimodel\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-05T08:41:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-16T14:48:14+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg\" \/>\n<meta name=\"author\" content=\"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@paudimodel\" \/>\n<meta name=\"twitter:site\" content=\"@paudimodel\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/\"},\"author\":{\"name\":\"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/person\\\/9bd9c57b7295e923a1c9956e891ebcbb\"},\"headline\":\"2017 International ToyFair in Nuremberg &#8211; February 1 &#8211; 6th\",\"datePublished\":\"2017-02-05T08:41:21+00:00\",\"dateModified\":\"2017-04-16T14:48:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/\"},\"wordCount\":30,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.imodelcar.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/toys-2-1024x724.jpg\",\"keywords\":[\"1:18 die-cast model car\",\"car model\",\"International ToyFair\",\"model car\",\"toyfair\"],\"articleSection\":[\"Interactive blog\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/\",\"name\":\"2017 International ToyFair in Nuremberg - February 1 - 6th - Paudi Model | High Quality Diecast Model\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.imodelcar.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/toys-2-1024x724.jpg\",\"datePublished\":\"2017-02-05T08:41:21+00:00\",\"dateModified\":\"2017-04-16T14:48:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.imodelcar.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/toys-2-1024x724.jpg\",\"contentUrl\":\"http:\\\/\\\/www.imodelcar.com\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/toys-2-1024x724.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/2017-international-toyfair-nuremberg-february-1-6th\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.paudimodel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2017 International ToyFair in Nuremberg &#8211; February 1 &#8211; 6th\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"name\":\"Paudi Model | High Quality Diecast Model\",\"description\":\"Shop For Diecast Models From Top-Rated Brands Like Dealer Edition, Paudi, Kyosho, Autoart &amp; More. Low Online Prices. Super-Detailed Models.Find Your Make &amp; Model.Huge Selection. Satisfaction Guaranteed. Types: Diecast Model Cars, Diecast Model Trucks.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\"},\"alternateName\":\"Scale model design, development and production\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.paudimodel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\",\"name\":\"Guangzhou Paudi Model Technology Ltd.\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Guangzhou Paudi Model Technology Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook\\\/paudimodel\",\"https:\\\/\\\/x.com\\\/paudimodel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/person\\\/9bd9c57b7295e923a1c9956e891ebcbb\",\"name\":\"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936\",\"caption\":\"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001\"},\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/de\\\/author\\\/news001\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"2017 International ToyFair in Nuremberg - February 1 - 6th - Paudi Model | High Quality Diecast Model","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paudimodel.com\/de\/2017-international-toyfair-nuremberg-february-1-6th\/","og_locale":"de_DE","og_type":"article","og_title":"2017 International ToyFair in Nuremberg - February 1 - 6th","og_url":"https:\/\/www.paudimodel.com\/de\/2017-international-toyfair-nuremberg-february-1-6th\/","og_site_name":"Paudi Model | High Quality Diecast Model","article_publisher":"https:\/\/www.facebook\/paudimodel","article_published_time":"2017-02-05T08:41:21+00:00","article_modified_time":"2017-04-16T14:48:14+00:00","og_image":[{"url":"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg","type":"","width":"","height":""}],"author":"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001","twitter_card":"summary_large_image","twitter_creator":"@paudimodel","twitter_site":"@paudimodel","twitter_misc":{"Verfasst von":"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#article","isPartOf":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/"},"author":{"name":"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001","@id":"https:\/\/www.paudimodel.com\/#\/schema\/person\/9bd9c57b7295e923a1c9956e891ebcbb"},"headline":"2017 International ToyFair in Nuremberg &#8211; February 1 &#8211; 6th","datePublished":"2017-02-05T08:41:21+00:00","dateModified":"2017-04-16T14:48:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/"},"wordCount":30,"commentCount":0,"publisher":{"@id":"https:\/\/www.paudimodel.com\/#organization"},"image":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#primaryimage"},"thumbnailUrl":"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg","keywords":["1:18 die-cast model car","car model","International ToyFair","model car","toyfair"],"articleSection":["Interactive blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/","url":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/","name":"2017 International ToyFair in Nuremberg - February 1 - 6th - Paudi Model | High Quality Diecast Model","isPartOf":{"@id":"https:\/\/www.paudimodel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#primaryimage"},"image":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#primaryimage"},"thumbnailUrl":"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg","datePublished":"2017-02-05T08:41:21+00:00","dateModified":"2017-04-16T14:48:14+00:00","breadcrumb":{"@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#primaryimage","url":"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg","contentUrl":"http:\/\/www.imodelcar.com\/wp-content\/uploads\/2016\/11\/toys-2-1024x724.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.paudimodel.com\/2017-international-toyfair-nuremberg-february-1-6th\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paudimodel.com\/"},{"@type":"ListItem","position":2,"name":"2017 International ToyFair in Nuremberg &#8211; February 1 &#8211; 6th"}]},{"@type":"WebSite","@id":"https:\/\/www.paudimodel.com\/#website","url":"https:\/\/www.paudimodel.com\/","name":"Paudi-Modell | Hochwertiges Druckgussmodell","description":"Kaufen Sie Druckgussmodelle von Top-Marken wie Dealer Edition, Paudi, Kyosho, Autoart und mehr. G\u00fcnstige Online-Preise. Superdetaillierte Modelle. Finden Sie Ihre Marke und Ihr Modell. Riesige Auswahl. Zufriedenheitsgarantie. Typen: Druckguss-Modellautos, Druckguss-Modell-LKWs.","publisher":{"@id":"https:\/\/www.paudimodel.com\/#organization"},"alternateName":"Scale model design, development and production","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paudimodel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.paudimodel.com\/#organization","name":"Guangzhou Paudi Model Technology Ltd.","url":"https:\/\/www.paudimodel.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","width":696,"height":696,"caption":"Guangzhou Paudi Model Technology Ltd."},"image":{"@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook\/paudimodel","https:\/\/x.com\/paudimodel"]},{"@type":"Person","@id":"https:\/\/www.paudimodel.com\/#\/schema\/person\/9bd9c57b7295e923a1c9956e891ebcbb","name":"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936","url":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/9cd9cb7125aa479981eb93d5a9f6fc57.jpg?ver=1778667936","caption":"\u666e\u8fea\u6a21\u578b, \u65b0\u95fb\u7f16\u8f91\u5458001"},"url":"https:\/\/www.paudimodel.com\/de\/author\/news001\/"}]}},"_links":{"self":[{"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/posts\/43251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/comments?post=43251"}],"version-history":[{"count":0,"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/posts\/43251\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/media?parent=43251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/categories?post=43251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paudimodel.com\/de\/wp-json\/wp\/v2\/tags?post=43251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}