{"id":56577,"date":"2019-02-11T02:59:43","date_gmt":"2019-02-11T02:59:43","guid":{"rendered":"https:\/\/www.paudimodel.com\/?post_type=portfolio&#038;p=56577"},"modified":"2019-07-28T10:45:21","modified_gmt":"2019-07-28T10:45:21","slug":"infiniti-qx60-2014-special-customized-version","status":"publish","type":"portfolio","link":"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/","title":{"rendered":"Infiniti QX60 2014 Special customized version"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-afjqbfl-10617abdef65e588d71628b816b5bb57\">\n.flex_column.av-afjqbfl-10617abdef65e588d71628b816b5bb57{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-afjqbfl-10617abdef65e588d71628b816b5bb57 av_one_half  avia-builder-el-0  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jrzqu58v-a1f2e7594279342f672c3dc44cc19827\">\n#top .avia-gallery.av-jrzqu58v-a1f2e7594279342f672c3dc44cc19827 .avia-gallery-thumb a{\nwidth:20%;\n}\n<\/style>\n<div  class='avia-gallery av-jrzqu58v-a1f2e7594279342f672c3dc44cc19827 avia_animate_when_visible  avia-builder-el-1  el_before_av_slideshow  avia-builder-el-first  avia_lazyload avia-gallery-animate avia-gallery-1'  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><meta itemprop=\"contentURL\" content=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/\"><div class='avia-gallery-thumb'><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-300x205.jpg 300w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-495x377.jpg' class='first_thumb lightbox ' data-onclick='1' title='1'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56700 avia-img-lazy-loading-not-56700\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-300x205.jpg\" width=\"300\" height=\"205\"  title='1' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-300x205.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56700 avia-img-lazy-loading-56700\"  width=\"495\" height=\"377\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-2-495x377.jpg\" title='1' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-300x205.jpg 300w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-495x377.jpg' class='lightbox ' data-onclick='2' title='2'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56703 avia-img-lazy-loading-not-56703\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-300x205.jpg\" width=\"300\" height=\"205\"  title='2' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-300x205.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56703 avia-img-lazy-loading-56703\"  width=\"495\" height=\"377\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/2-1-495x377.jpg\" title='2' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1.jpg 554w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-450x301.jpg 450w\" data-sizes=\"(max-width: 554px) 100vw, 554px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-495x371.jpg' class='lightbox ' data-onclick='3' title='3'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56706 avia-img-lazy-loading-not-56706\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-300x201.jpg\" width=\"300\" height=\"201\"  title='3' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-450x301.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1.jpg 554w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56706 avia-img-lazy-loading-56706\"  width=\"495\" height=\"371\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/3-1-495x371.jpg\" title='3' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-300x200.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-450x300.jpg 450w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-495x369.jpg' class='lightbox ' data-onclick='4' title='4'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56709 avia-img-lazy-loading-not-56709\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-300x200.jpg\" width=\"300\" height=\"200\"  title='4' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-300x200.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-450x300.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56709 avia-img-lazy-loading-56709\"  width=\"495\" height=\"369\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/4-2-495x369.jpg\" title='4' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1.jpg 533w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-300x205.jpg 300w\" data-sizes=\"(max-width: 533px) 100vw, 533px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-495x364.jpg' class='lightbox ' data-onclick='5' title='5'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56712 avia-img-lazy-loading-not-56712\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-300x205.jpg\" width=\"300\" height=\"205\"  title='5' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-300x205.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1.jpg 533w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56712 avia-img-lazy-loading-56712\"  width=\"495\" height=\"364\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/5-1-495x364.jpg\" title='5' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-450x308.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-300x205.jpg 300w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-495x378.jpg' class='first_thumb lightbox ' data-onclick='6' title='6'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56715 avia-img-lazy-loading-not-56715\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-300x205.jpg\" width=\"300\" height=\"205\"  title='6' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-300x205.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-450x308.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56715 avia-img-lazy-loading-56715\"  width=\"495\" height=\"378\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/6-1-495x378.jpg\" title='6' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1.jpg 552w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-300x200.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-450x300.jpg 450w\" data-sizes=\"(max-width: 552px) 100vw, 552px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-495x368.jpg' class='lightbox ' data-onclick='7' title='7'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56718 avia-img-lazy-loading-not-56718\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-300x200.jpg\" width=\"300\" height=\"200\"  title='7' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-300x200.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-450x300.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1.jpg 552w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56718 avia-img-lazy-loading-56718\"  width=\"495\" height=\"368\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/7-1-495x368.jpg\" title='7' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-450x301.jpg 450w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-495x370.jpg' class='lightbox ' data-onclick='8' title='8'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56721 avia-img-lazy-loading-not-56721\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-300x201.jpg\" width=\"300\" height=\"201\"  title='8' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-450x301.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56721 avia-img-lazy-loading-56721\"  width=\"495\" height=\"370\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/8-1-495x370.jpg\" title='8' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-450x301.jpg 450w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-495x370.jpg' class='lightbox ' data-onclick='9' title='9'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56724 avia-img-lazy-loading-not-56724\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-300x201.jpg\" width=\"300\" height=\"201\"  title='9' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-300x201.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-450x301.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56724 avia-img-lazy-loading-56724\"  width=\"495\" height=\"370\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/9-1-495x370.jpg\" title='9' alt='' \/><\/div><\/a><a href=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1.jpg\" data-srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1.jpg 553w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-300x205.jpg 300w\" data-sizes=\"(max-width: 553px) 100vw, 553px\" data-rel='gallery-1' data-prev-img='https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-495x377.jpg' class='lightbox ' data-onclick='10' title='10'  itemprop=\"thumbnailUrl\"  ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-56727 avia-img-lazy-loading-not-56727\"   src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-300x205.jpg\" width=\"300\" height=\"205\"  title='10' alt='' srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-300x205.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-450x307.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1.jpg 553w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><div class='big-prev-fake'><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-56727 avia-img-lazy-loading-56727\"  width=\"495\" height=\"377\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/10-1-495x377.jpg\" title='10' alt='' \/><\/div><\/a><\/div><\/div><br \/>\n<div  class='avia-slideshow av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82 avia-slideshow-featured av_slideshow avia-slide-slider  avia-builder-el-2  el_after_av_gallery  avia-builder-el-last  av-slideshow-ui av-control-default av-slideshow-manual av-loop-once av-loop-manual-endless av-default-height-applied avia-slideshow-1' data-slideshow-options=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;autoplay&quot;:false,&quot;loop_autoplay&quot;:&quot;once&quot;,&quot;interval&quot;:5,&quot;loop_manual&quot;:&quot;manual-endless&quot;,&quot;autoplay_stopper&quot;:false,&quot;noNavigation&quot;:false,&quot;bg_slider&quot;:false,&quot;keep_padding&quot;:false,&quot;hoverpause&quot;:false,&quot;show_slide_delay&quot;:0}\"  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><ul class='avia-slideshow-inner ' style='padding-bottom: 66.460587326121%;'><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__0  slide-1 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27697 avia-img-lazy-loading-not-27697\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_12' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__1  slide-2 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27696 avia-img-lazy-loading-not-27696\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_11-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_11' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_11-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_11-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_11-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_11-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__2  slide-3 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27699 avia-img-lazy-loading-not-27699\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_14-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_14' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_14-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_14-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_14-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_14-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__3  slide-4 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27698 avia-img-lazy-loading-not-27698\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_13-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_13' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_13-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_13-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_13-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_13-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__4  slide-5 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27695 avia-img-lazy-loading-not-27695\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_10-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_10' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_10-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_10-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_10-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_10-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__5  slide-6 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27694 avia-img-lazy-loading-not-27694\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_09-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_09' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_09-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_09-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_09-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_09-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__9  slide-7 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27693 avia-img-lazy-loading-not-27693\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_08-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_08' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_08-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_08-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_08-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_08-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__10  slide-8 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27692 avia-img-lazy-loading-not-27692\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_07-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_07' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_07-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_07-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_07-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_07-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__11  slide-9 slide-odd'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27691 avia-img-lazy-loading-not-27691\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_06-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_06' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_06-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_06-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_06-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_06-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><li  class='avia-slideshow-slide av-js1dxkjf-f2a692b272ecc7c4da84b4d8f6051a82__12  slide-10 slide-even'><div data-rel='slideshow-1' class='avia-slide-wrap '   ><img decoding=\"async\" fetchpriority=\"high\" class=\"wp-image-27690 avia-img-lazy-loading-not-27690\"  src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_05-1.jpg\" width=\"647\" height=\"430\" title='Infiniti_QX60_2014_Ga_05' alt=''  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_05-1.jpg 990w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_05-1-300x199.jpg 300w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_05-1-450x299.jpg 450w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_05-1-768x510.jpg 768w\" sizes=\"(max-width: 647px) 100vw, 647px\" \/><\/div><\/li><\/ul><div class='avia-slideshow-arrows avia-slideshow-controls' ><a href='#prev' class='prev-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='left-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Previous\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-1' aria-describedby='av-svg-desc-1' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-1'>Previous<\/title>\n<desc id='av-svg-desc-1'>Previous<\/desc>\n<path d=\"M14.464 27.84q0.832 0.832 0 1.536-0.832 0.832-1.536 0l-12.544-12.608q-0.768-0.768 0-1.6l12.544-12.608q0.704-0.832 1.536 0 0.832 0.704 0 1.536l-11.456 11.904z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Previous<\/span><\/a><a href='#next' class='next-slide  avia-svg-icon avia-font-svg_entypo-fontello' data-av_svg_icon='right-open-big' data-av_iconset='svg_entypo-fontello' tabindex='-1' title=\"Next\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"32\" viewBox=\"0 0 15 32\" preserveAspectRatio=\"xMidYMid meet\" aria-labelledby='av-svg-title-2' aria-describedby='av-svg-desc-2' role=\"graphics-symbol\" aria-hidden=\"true\">\n<title id='av-svg-title-2'>Next<\/title>\n<desc id='av-svg-desc-2'>Next<\/desc>\n<path d=\"M0.416 27.84l11.456-11.84-11.456-11.904q-0.832-0.832 0-1.536 0.832-0.832 1.536 0l12.544 12.608q0.768 0.832 0 1.6l-12.544 12.608q-0.704 0.832-1.536 0-0.832-0.704 0-1.536z\"><\/path>\n<\/svg><span class='avia_hidden_link_text'>Next<\/span><\/a><\/div><div class='avia-slideshow-dots avia-slideshow-controls'><a href='#1' class='goto-slide active' >1<\/a><a href='#2' class='goto-slide ' >2<\/a><a href='#3' class='goto-slide ' >3<\/a><a href='#4' class='goto-slide ' >4<\/a><a href='#5' class='goto-slide ' >5<\/a><a href='#6' class='goto-slide ' >6<\/a><a href='#7' class='goto-slide ' >7<\/a><a href='#8' class='goto-slide ' >8<\/a><a href='#9' class='goto-slide ' >9<\/a><a href='#10' class='goto-slide ' >10<\/a><\/div><\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-e5hu01-95c721d3940698db41d006844d0c8194\">\n.flex_column.av-e5hu01-95c721d3940698db41d006844d0c8194{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-e5hu01-95c721d3940698db41d006844d0c8194 av_one_half  avia-builder-el-3  el_after_av_one_half  el_before_av_one_half  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2mewlxd-e8e8c16a0db1181ad0b00b5c511f86be\">\n#top .av-special-heading.av-2mewlxd-e8e8c16a0db1181ad0b00b5c511f86be{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-2mewlxd-e8e8c16a0db1181ad0b00b5c511f86be .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-2mewlxd-e8e8c16a0db1181ad0b00b5c511f86be .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-2mewlxd-e8e8c16a0db1181ad0b00b5c511f86be av-special-heading-h3  avia-builder-el-4  el_before_av_textblock  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >1\/18 INFINITI QX60 2014 DIE-CAST MODEL CAR<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-js1enm45-196e53bbb6e4e4190529829b8722da8f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Infiniti QX60 has eye-catching 7-seater, 245 horsepower QR25 engine, come into the market in 2012. Success come with its solid and tough industrial design, flexible and spacious internal space, Infiniti QX60 awarded Ward&#8217;s Auto 10 Best Interiors for 2012.<\/p>\n<p>Features: Paudi Model do high simulation with these perfect design. The diecast car is made of zinc alloy and ABS plastic. It consists of total 315 parts and reproduces the real car function. For QX60 model, there are 17 movable places.<\/p>\n<\/div><\/section><br \/>\n<div  class='togglecontainer av-js1es4cg-810ea0d95d6352a272bec4879633406c  avia-builder-el-6  el_after_av_textblock  avia-builder-el-last  toggle_close_all' >\n<section class='av_toggle_section av-34vvnhd-592ee328acde555ddd04344231866d94'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-1' data-fake-id='#toggle-id-1' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-1' data-slide-speed=\"200\" data-title=\"Brand:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Brand:\" data-aria_expanded=\"Click to collapse: Brand:\">Brand:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-1' aria-labelledby='toggle-toggle-id-1' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-47168\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/02\/infiniti.png\" alt=\"\" width=\"90\" height=\"90\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/02\/infiniti.png 220w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/02\/infiniti-100x100.png 100w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/02\/infiniti-150x150.png 150w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/><\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-2q1cokh-dfdcfb62efc76a0cf2fb0a94159136bf'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-2' data-fake-id='#toggle-id-2' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-2' data-slide-speed=\"200\" data-title=\"Weight:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Weight:\" data-aria_expanded=\"Click to collapse: Weight:\">Weight:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-2' aria-labelledby='toggle-toggle-id-2' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>2.0kg<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-24xappd-9d022233be95720f3bca73e2bdbca700'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-3' data-fake-id='#toggle-id-3' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-3' data-slide-speed=\"200\" data-title=\"Scale:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Scale:\" data-aria_expanded=\"Click to collapse: Scale:\">Scale:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-3' aria-labelledby='toggle-toggle-id-3' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>1\/18<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-1msj21t-d5bff30b03ef90010bef51a0a03bdfd1'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-4' data-fake-id='#toggle-id-4' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-4' data-slide-speed=\"200\" data-title=\"Packing:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Packing:\" data-aria_expanded=\"Click to collapse: Packing:\">Packing:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-4' aria-labelledby='toggle-toggle-id-4' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>Cartons box<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-1y44esh-01e22ad3d65959e5c3f9427de227b2e0'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-5' data-fake-id='#toggle-id-5' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-5' data-slide-speed=\"200\" data-title=\"Size:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Size:\" data-aria_expanded=\"Click to collapse: Size:\">Size:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-5' aria-labelledby='toggle-toggle-id-5' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>278\u00d7109\u00d797mm(L*B*H)<\/p>\n<\/div><\/div><\/div><\/section>\n<section class='av_toggle_section av-1oljlb5-5adc01f4554cbc679ddedd52258b6b32'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div role=\"tablist\" class=\"single_toggle\" data-tags=\"{All} \"  ><p id='toggle-toggle-id-6' data-fake-id='#toggle-id-6' class='toggler  av-title-above '  itemprop=\"headline\"  role='tab' tabindex='0' aria-controls='toggle-id-6' data-slide-speed=\"200\" data-title=\"Date of Produced:\" data-title-open=\"\" data-aria_collapsed=\"Click to expand: Date of Produced:\" data-aria_expanded=\"Click to collapse: Date of Produced:\">Date of Produced:<span class=\"toggle_icon\"><span class=\"vert_icon\"><\/span><span class=\"hor_icon\"><\/span><\/span><\/p><div id='toggle-id-6' aria-labelledby='toggle-toggle-id-6' role='region' class='toggle_wrap  av-title-above'  ><div class='toggle_content invers-color '  itemprop=\"text\" ><p>2014<\/p>\n<\/div><\/div><\/div><\/section>\n<\/div><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-4wmdoh-b537d2e0fa6b33cfa21021da33041348\">\n.flex_column.av-4wmdoh-b537d2e0fa6b33cfa21021da33041348{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-4wmdoh-b537d2e0fa6b33cfa21021da33041348 av_one_half  avia-builder-el-7  el_after_av_one_half  el_before_av_one_half  first flex_column_div av-zero-column-padding  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1ap0h1d-4a382a264ff2403adb55f90b204bd35f\">\n#top .av-special-heading.av-1ap0h1d-4a382a264ff2403adb55f90b204bd35f{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-1ap0h1d-4a382a264ff2403adb55f90b204bd35f .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-1ap0h1d-4a382a264ff2403adb55f90b204bd35f .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-1ap0h1d-4a382a264ff2403adb55f90b204bd35f av-special-heading-h3  avia-builder-el-8  el_before_av_textblock  avia-builder-el-first '><h3 class='av-special-heading-tag '  itemprop=\"headline\"  >Artist Cai Guoqiang and Infiniti Open the <span class='special_amp'>&#8220;<\/span>Dare to Love<span class='special_amp'>&#8221;<\/span> Tour<\/h3><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-js30mnw9-b2718e663eb384ad59588b1bc3531f9f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>The car was created by 15 teenagers, including 8 children with autism, watching the work of &#8220;Nine Waves&#8221; on the spot. The resulting single painting was integrated into a complete work by the artist Mr. Cai Guoqiang and eventually presented as the Infiniti QX60 Hybrid Art Car. Being full of children&#8217;s innate and unrestrained imagination, the art car will serve as an important symbol of Infiniti&#8217;s &#8220;Dare to Love&#8221; charity action-care program for children with autism, calling on the public to understand and care for the autistic group.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-td01wh-c0c7d2d5ceaa1813a8ebb0ba4cb5c522\">\n.flex_column.av-td01wh-c0c7d2d5ceaa1813a8ebb0ba4cb5c522{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-td01wh-c0c7d2d5ceaa1813a8ebb0ba4cb5c522 av_one_half  avia-builder-el-10  el_after_av_one_half  el_before_av_one_full  flex_column_div av-zero-column-padding  column-top-margin'     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-js30uwp2-8fe5717c2ef3992a04817d3373284158\">\n.avia-image-container.av-js30uwp2-8fe5717c2ef3992a04817d3373284158 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-js30uwp2-8fe5717c2ef3992a04817d3373284158 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-js30uwp2-8fe5717c2ef3992a04817d3373284158 av-styling- avia-align-center  avia-builder-el-11  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-56697 avia-img-lazy-loading-not-56697 avia_image ' src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/QQX51T8ZS9P4XCB_2U2-800x430.jpg\" alt='' title='Q)%QX51T8ZS9P4XCB_]2}U2'  height=\"430\" width=\"800\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l68cap-724ce2522b344c738c7fe7e2e28cab54\">\n.flex_column.av-l68cap-724ce2522b344c738c7fe7e2e28cab54{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-l68cap-724ce2522b344c738c7fe7e2e28cab54 av_one_full  avia-builder-el-12  el_after_av_one_half  avia-builder-el-last  first flex_column_div av-zero-column-padding  column-top-margin'     ><div  id=\"av-sc-portfolio-1\"  class=\"av-portfolio-grid-sorting-container\"><div class='sort_width_container  av-sort-yes' data-portfolio-id='1' ><div id='js_sort_items' ><div class='sort_by_cat hidden'><a href=\"#\" data-filter=\"all_sort\" class=\"all_sort_button active_sort\"><span class=\"inner_sort_button\"><span>All<\/span><small class=\"av-cat-count\"> 16 <\/small><\/span><\/a><span class=\"text-sep customization-case_sort_sep\">\/<\/span><a href=\"#\" data-filter=\"customization-case_sort\" class=\"customization-case_sort_button\" ><span class=\"inner_sort_button\"><span>Customization case<\/span><small class=\"av-cat-count\"> 12 <\/small><\/span><\/a><\/div><\/div><\/div><div  class=' grid-sort-container isotope   no_margin-container with-excerpt-container grid-total-even grid-col-5 grid-links-' data-portfolio-id='1'><div data-ajax-id='77701' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-77701 grid-entry-overview grid-loop-1 grid-parity-odd  1-24-scale_sort customization-case_sort  av_one_fifth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/vinfast-vf8-1-24-miniature-model\/\" title='Vinfast VF8 1\/24 miniature model'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF8_B_03-260x185.jpg\" class=\"wp-image-79318 avia-img-lazy-loading-not-79318 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF8_B_03-260x185.jpg 260w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF8_B_03-18x12.jpg 18w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF8_B_03-845x600.jpg 845w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vinfast VF8 1\/24 miniature model\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/vinfast-vf8-1-24-miniature-model\/' title='Vinfast VF8 1\/24 miniature model'>Vinfast VF8 1\/24 miniature model<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='77647' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-77647 grid-entry-overview grid-loop-2 grid-parity-even  1-24-scale_sort customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-24-scale-vinfast-vf9-miniature-model\/\" title='1\/24 Scale Vinfast VF9 miniature model'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF9_green_03-260x185.jpg\" class=\"wp-image-77649 avia-img-lazy-loading-not-77649 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF9_green_03-260x185.jpg 260w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2024\/02\/1_24_VINFAST_VF9_green_03-845x600.jpg 845w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1\/24 Scale Vinfast VF9 miniature model\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-24-scale-vinfast-vf9-miniature-model\/' title='1\/24 Scale Vinfast VF9 miniature model'>1\/24 Scale Vinfast VF9 miniature model<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='76330' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-76330 grid-entry-overview grid-loop-3 grid-parity-odd  customization-case_sort product-catalog_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/118-nissan-ariya-die-cast-model-car\/\" title='1:18 Nissan Ariya Die-cast Model Car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2022\/10\/Ariya-21-260x185.jpg\" class=\"wp-image-76359 avia-img-lazy-loading-not-76359 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" srcset=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2022\/10\/Ariya-21-260x185.jpg 260w, https:\/\/www.paudimodel.com\/wp-content\/uploads\/2022\/10\/Ariya-21-845x600.jpg 845w\" sizes=\"(max-width: 260px) 100vw, 260px\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1:18 Nissan Ariya Die-cast Model Car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/118-nissan-ariya-die-cast-model-car\/' title='1:18 Nissan Ariya Die-cast Model Car'>1:18 Nissan Ariya Die-cast Model Car<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='76056' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-76056 grid-entry-overview grid-loop-4 grid-parity-even  customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/2022-118-citroen-c5-aircross-die-cast-model-car\/\" title='2022 1:18 Citroen C5 Aircross Die-cast Model Car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2022\/09\/C5-4-LWH-260x185.png\" class=\"wp-image-76085 avia-img-lazy-loading-not-76085 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 2022 1:18 Citroen C5 Aircross Die-cast Model Car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/2022-118-citroen-c5-aircross-die-cast-model-car\/' title='2022 1:18 Citroen C5 Aircross Die-cast Model Car'>2022 1:18 Citroen C5 Aircross Die-cast Model Car<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='70276' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-70276 grid-entry-overview grid-loop-5 grid-parity-odd  infiniti-global-miniature-car_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-30th-anniversary-164-miniature-set\/\" title='Infiniti 30th Anniversary 1:64 Miniature Set'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2021\/03\/\u56db\u4ef6\u5957\u9650\u91cf\u7248-07-260x185.jpg\" class=\"wp-image-70310 avia-img-lazy-loading-not-70310 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Infiniti 30th Anniversary 1:64 Miniature Set\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-30th-anniversary-164-miniature-set\/' title='Infiniti 30th Anniversary 1:64 Miniature Set'>Infiniti 30th Anniversary 1:64 Miniature Set<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='67167' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-67167 grid-entry-overview grid-loop-6 grid-parity-even  customization-case_sort  av_one_fifth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-43-scale-exeed-lx-diecast-model-car\/\" title='1\/43 SCALE EXEED LX DIECAST MODEL CAR'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2020\/04\/43\u661f\u9014LX-15-260x185.jpg\" class=\"wp-image-67174 avia-img-lazy-loading-not-67174 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1\/43 SCALE EXEED LX DIECAST MODEL CAR\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-43-scale-exeed-lx-diecast-model-car\/' title='1\/43 SCALE EXEED LX DIECAST MODEL CAR'>1\/43 SCALE EXEED LX DIECAST MODEL CAR<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='67098' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-67098 grid-entry-overview grid-loop-7 grid-parity-odd  customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-18-scale-the-new-tiggo-7-diecast-model-car\/\" title='1\/18 SCALE THE NEW TIGGO 7 DIECAST MODEL CAR'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2020\/04\/18\u745e\u864e7-12-260x185.jpg\" class=\"wp-image-67102 avia-img-lazy-loading-not-67102 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1\/18 SCALE THE NEW TIGGO 7 DIECAST MODEL CAR\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-18-scale-the-new-tiggo-7-diecast-model-car\/' title='1\/18 SCALE THE NEW TIGGO 7 DIECAST MODEL CAR'>1\/18 SCALE THE NEW TIGGO 7 DIECAST MODEL CAR<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='66956' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-66956 grid-entry-overview grid-loop-8 grid-parity-even  customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/66956\/\" title='1\/18 SCALE EXEED LX DIECAST MODEL CAR'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2020\/04\/18\u661f\u9014LX-11-260x185.jpg\" class=\"wp-image-66972 avia-img-lazy-loading-not-66972 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1\/18 SCALE EXEED LX DIECAST MODEL CAR\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/66956\/' title='1\/18 SCALE EXEED LX DIECAST MODEL CAR'>1\/18 SCALE EXEED LX DIECAST MODEL CAR<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='65092' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-65092 grid-entry-overview grid-loop-9 grid-parity-odd  customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/saic-iveco-hongyan-diecast-model-truck\/\" title='SAIC IVECO HONGYAN DIECAST MODEL TRUCK'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2020\/02\/\u5fae\u4fe1\u56fe\u7247_20200210171403-260x185.jpg\" class=\"wp-image-65113 avia-img-lazy-loading-not-65113 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: SAIC IVECO HONGYAN DIECAST MODEL TRUCK\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/saic-iveco-hongyan-diecast-model-truck\/' title='SAIC IVECO HONGYAN DIECAST MODEL TRUCK'>SAIC IVECO HONGYAN DIECAST MODEL TRUCK<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='65118' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-65118 grid-entry-overview grid-loop-10 grid-parity-even  customization-case_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-18-scale-chery-exeed-lx-diecast-model-car\/\" title='1\/18 SCALE CHERY EXEED LX DIECAST MODEL CAR'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2020\/02\/\u5fae\u4fe1\u56fe\u7247_20200210174041-260x185.jpg\" class=\"wp-image-65125 avia-img-lazy-loading-not-65125 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: 1\/18 SCALE CHERY EXEED LX DIECAST MODEL CAR\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-18-scale-chery-exeed-lx-diecast-model-car\/' title='1\/18 SCALE CHERY EXEED LX DIECAST MODEL CAR'>1\/18 SCALE CHERY EXEED LX DIECAST MODEL CAR<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='61014' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-61014 grid-entry-overview grid-loop-11 grid-parity-odd  1-24-scale_sort customization-case_sort  av_one_fifth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/61014\/\" title='Vinfast LUX A2.0 SUV MODEL CAR 1\/18 SCALE'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/09\/18-VINFAST-05-260x185.png\" class=\"wp-image-60966 avia-img-lazy-loading-not-60966 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vinfast LUX A2.0 SUV MODEL CAR 1\/18 SCALE\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/61014\/' title='Vinfast LUX A2.0 SUV MODEL CAR 1\/18 SCALE'>Vinfast LUX A2.0 SUV MODEL CAR 1\/18 SCALE<\/a><\/h3><\/header><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='58493' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-58493 grid-entry-overview grid-loop-12 grid-parity-even  infiniti-global-miniature-car_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx30-miniature-car\/\" title='INFINITI QX30 Miniature car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-64-QX30-Gray-07-260x185.png\" class=\"wp-image-56781 avia-img-lazy-loading-not-56781 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: INFINITI QX30 Miniature car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx30-miniature-car\/' title='INFINITI QX30 Miniature car'>INFINITI QX30 Miniature car<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >1\/64 scale INFINITI QX30 30th Miniature model car<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='58470' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-58470 grid-entry-overview grid-loop-13 grid-parity-odd  infiniti-global-miniature-car_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-q60-miniature-car\/\" title='INFINITI Q60 Miniature car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/04\/64-Infiniti-Q60-2018-red-07-260x185.png\" class=\"wp-image-58010 avia-img-lazy-loading-not-58010 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: INFINITI Q60 Miniature car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-q60-miniature-car\/' title='INFINITI Q60 Miniature car'>INFINITI Q60 Miniature car<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >1\/64 scale INFINITI Q60 30th Miniature model car<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='58377' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-58377 grid-entry-overview grid-loop-14 grid-parity-even  infiniti-global-miniature-car_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/164-infiniti-miniature-car\/\" title='INFINITI QX60 Miniature car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/04\/64-Infiniti-QX60-2018-blue-01-260x185.gif\" class=\"wp-image-57956 avia-img-lazy-loading-not-57956 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: INFINITI QX60 Miniature car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/164-infiniti-miniature-car\/' title='INFINITI QX60 Miniature car'>INFINITI QX60 Miniature car<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >1\/64 scale INFINITI QX60 30th Miniature model car<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='58397' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-58397 grid-entry-overview grid-loop-15 grid-parity-odd  customization-case_sort infiniti-global-miniature-car_sort  av_one_fifth  default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/164-infiniti-qx50-miniature-car\/\" title='INFINITI QX50 Miniature car'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/1-64-QX50-2019-Gray-04-260x185.png\" class=\"wp-image-56795 avia-img-lazy-loading-not-56795 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: INFINITI QX50 Miniature car\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/164-infiniti-qx50-miniature-car\/' title='INFINITI QX50 Miniature car'>INFINITI QX50 Miniature car<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >1\/64 scale INFINITI QX50 30th Miniature model car<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><div data-ajax-id='56853' class=' grid-entry flex_column isotope-item all_sort no_margin post-entry post-entry-56853 grid-entry-overview grid-loop-16 grid-parity-even  post-entry-last  1-24-scale_sort customization-case_sort  av_one_fifth first default_av_fullwidth '><article class='main_color inner-entry'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><a href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-24-scale-vinfast-lux-a2-0-sedan-model-car\/\" title='Vinfast LUX A2.0 SEDAN MODEL CAR 1\/24 SCALE'  data-rel='grid-1' class='grid-image avia-hover-fx'> <img decoding=\"async\" fetchpriority=\"high\" width=\"260\" height=\"185\" src=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2019\/02\/VINFAST-LUX-A2.0-SEDAN_01-260x185.jpg\" class=\"wp-image-56890 avia-img-lazy-loading-not-56890 attachment-portfolio_small size-portfolio_small wp-post-image\" alt=\"\" \/><\/a><div class='grid-content'><div class='avia-arrow'><\/div><header class=\"entry-content-header\" aria-label=\"Portfolio: Vinfast LUX A2.0 SEDAN MODEL CAR 1\/24 SCALE\"><h3 class='grid-entry-title entry-title '  itemprop=\"headline\" ><a href='https:\/\/www.paudimodel.com\/en\/portfolio-item\/1-24-scale-vinfast-lux-a2-0-sedan-model-car\/' title='Vinfast LUX A2.0 SEDAN MODEL CAR 1\/24 SCALE'>Vinfast LUX A2.0 SEDAN MODEL CAR 1\/24 SCALE<\/a><\/h3><\/header><div class='grid-entry-excerpt entry-content'  itemprop=\"text\" >Vinfast LUX A2.0 SEDAN DIECAST MODEL CAR 1\/24 SCALE<\/div><\/div><footer class=\"entry-footer\"><\/footer><\/article><\/div><\/div><\/div>   <!--   class=\"av-portfolio-grid-sorting-container\"  --><div class='pagination-wrap  '><nav class='pagination'><span class='pagination-meta'>Page 1 of 2<\/span><span class='current'>1<\/span><a href='https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/portfolio\/56577\/?avia-element-paging=2' class='inactive next_page' >2<\/a><\/nav>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>1\/18 scale Infiniti QX60 2014 Special customized version diecast model car<\/p>\n","protected":false},"author":0,"featured_media":27697,"comment_status":"open","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[2217],"class_list":["post-56577","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-customization-case"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Infiniti QX60 2014 Special customized version - Paudi Model | High Quality Diecast Model<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/?wmc-currency=USD\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Infiniti QX60 2014 Special customized version\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/?wmc-currency=USD\" \/>\n<meta property=\"og:site_name\" content=\"Paudi Model | High Quality Diecast Model\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook\/paudimodel\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-28T10:45:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@paudimodel\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/\",\"name\":\"Infiniti QX60 2014 Special customized version - Paudi Model | High Quality Diecast Model\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Infiniti_QX60_2014_Ga_12-1.jpg\",\"datePublished\":\"2019-02-11T02:59:43+00:00\",\"dateModified\":\"2019-07-28T10:45:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Infiniti_QX60_2014_Ga_12-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Infiniti_QX60_2014_Ga_12-1.jpg\",\"width\":990,\"height\":658},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/portfolio-item\\\/infiniti-qx60-2014-special-customized-version\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.paudimodel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Infiniti QX60 2014 Special customized version\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"name\":\"Paudi Model | High Quality Diecast Model\",\"description\":\"Shop For Diecast Models From Top-Rated Brands Like Dealer Edition, Paudi, Kyosho, Autoart &amp; More. Low Online Prices. Super-Detailed Models.Find Your Make &amp; Model.Huge Selection. Satisfaction Guaranteed. Types: Diecast Model Cars, Diecast Model Trucks.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\"},\"alternateName\":\"Scale model design, development and production\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.paudimodel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\",\"name\":\"Guangzhou Paudi Model Technology Ltd.\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Guangzhou Paudi Model Technology Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook\\\/paudimodel\",\"https:\\\/\\\/x.com\\\/paudimodel\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Infiniti QX60 2014 Special customized version - Paudi Model | High Quality Diecast Model","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/?wmc-currency=USD","og_locale":"en_US","og_type":"article","og_title":"Infiniti QX60 2014 Special customized version","og_url":"https:\/\/www.paudimodel.com\/en\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/?wmc-currency=USD","og_site_name":"Paudi Model | High Quality Diecast Model","article_publisher":"https:\/\/www.facebook\/paudimodel","article_modified_time":"2019-07-28T10:45:21+00:00","og_image":[{"width":990,"height":658,"url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@paudimodel","twitter_misc":{"Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/","url":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/","name":"Infiniti QX60 2014 Special customized version - Paudi Model | High Quality Diecast Model","isPartOf":{"@id":"https:\/\/www.paudimodel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/#primaryimage"},"image":{"@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg","datePublished":"2019-02-11T02:59:43+00:00","dateModified":"2019-07-28T10:45:21+00:00","breadcrumb":{"@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/#primaryimage","url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Infiniti_QX60_2014_Ga_12-1.jpg","width":990,"height":658},{"@type":"BreadcrumbList","@id":"https:\/\/www.paudimodel.com\/portfolio-item\/infiniti-qx60-2014-special-customized-version\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paudimodel.com\/"},{"@type":"ListItem","position":2,"name":"Infiniti QX60 2014 Special customized version"}]},{"@type":"WebSite","@id":"https:\/\/www.paudimodel.com\/#website","url":"https:\/\/www.paudimodel.com\/","name":"Paudi Model | High Quality Diecast Model","description":"Shop For Diecast Models From Top-Rated Brands Like Dealer Edition, Paudi, Kyosho, Autoart &amp; More. Low Online Prices. Super-Detailed Models.Find Your Make &amp; Model.Huge Selection. Satisfaction Guaranteed. Types: Diecast Model Cars, Diecast Model Trucks.","publisher":{"@id":"https:\/\/www.paudimodel.com\/#organization"},"alternateName":"Scale model design, development and production","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paudimodel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.paudimodel.com\/#organization","name":"Guangzhou Paudi Model Technology Ltd.","url":"https:\/\/www.paudimodel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","width":696,"height":696,"caption":"Guangzhou Paudi Model Technology Ltd."},"image":{"@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook\/paudimodel","https:\/\/x.com\/paudimodel"]}]}},"_links":{"self":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/portfolio\/56577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/comments?post=56577"}],"version-history":[{"count":0,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/portfolio\/56577\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/media\/27697"}],"wp:attachment":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/media?parent=56577"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/tags?post=56577"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/portfolio_entries?post=56577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}