{"id":47591,"date":"2017-04-18T09:42:36","date_gmt":"2017-04-18T01:42:36","guid":{"rendered":"http:\/\/www.paudimodel.com\/?p=47591"},"modified":"2017-05-01T17:33:00","modified_gmt":"2017-05-01T09:33:00","slug":"paudi-model-skoda-rapid-2013-118-scale-diecast-model-car","status":"publish","type":"post","link":"https:\/\/www.paudimodel.com\/en\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/","title":{"rendered":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car"},"content":{"rendered":"<div class='avia-iframe-wrap'><iframe loading=\"lazy\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/twi8myk1jhM?feature=oembed\" frameborder=\"0\" allow=\"autoplay; encrypted-media\" allowfullscreen><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":42687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[467,468,486,474,473,480,477],"class_list":["post-47591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-1-18-model-cars","tag-1-18-scale-model-cars","tag-118-die-cast-model-car","tag-car-model","tag-model-car","tag-scale-model-cars","tag-toy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Paudi Model Skoda Rapid 2013 1:18 scale diecast model car - Paudi Model | High Quality Diecast Model<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.paudimodel.com\/en\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/?wmc-currency=USD\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.paudimodel.com\/en\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/?wmc-currency=USD\" \/>\n<meta property=\"og:site_name\" content=\"Paudi Model | High Quality Diecast Model\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook\/paudimodel\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T01:42:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-05-01T09:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"990\" \/>\n\t<meta property=\"og:image:height\" content=\"658\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paudi_Products02\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@paudimodel\" \/>\n<meta name=\"twitter:site\" content=\"@paudimodel\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paudi_Products02\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/\"},\"author\":{\"name\":\"Paudi_Products02\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/person\\\/987cc7defc51ab0657b80c639bfd1a4c\"},\"headline\":\"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car\",\"datePublished\":\"2017-04-18T01:42:36+00:00\",\"dateModified\":\"2017-05-01T09:33:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/\"},\"wordCount\":17,\"commentCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Skoda_Rapid_2013_white_001-1.jpg\",\"keywords\":[\"1 18 model cars\",\"1 18 scale model cars\",\"1:18 die-cast model car\",\"car model\",\"model car\",\"scale model cars\",\"toy\"],\"articleSection\":[\"Interactive blog\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/\",\"name\":\"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car - Paudi Model | High Quality Diecast Model\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Skoda_Rapid_2013_white_001-1.jpg\",\"datePublished\":\"2017-04-18T01:42:36+00:00\",\"dateModified\":\"2017-05-01T09:33:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Skoda_Rapid_2013_white_001-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2016\\\/04\\\/Skoda_Rapid_2013_white_001-1.jpg\",\"width\":990,\"height\":658},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.paudimodel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#website\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"name\":\"Paudi Model | High Quality Diecast Model\",\"description\":\"Shop For Diecast Models From Top-Rated Brands Like Dealer Edition, Paudi, Kyosho, Autoart &amp; More. Low Online Prices. Super-Detailed Models.Find Your Make &amp; Model.Huge Selection. Satisfaction Guaranteed. Types: Diecast Model Cars, Diecast Model Trucks.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\"},\"alternateName\":\"Scale model design, development and production\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.paudimodel.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#organization\",\"name\":\"Guangzhou Paudi Model Technology Ltd.\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/696x696.png\",\"width\":696,\"height\":696,\"caption\":\"Guangzhou Paudi Model Technology Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook\\\/paudimodel\",\"https:\\\/\\\/x.com\\\/paudimodel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/#\\\/schema\\\/person\\\/987cc7defc51ab0657b80c639bfd1a4c\",\"name\":\"Paudi_Products02\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858\",\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858\",\"contentUrl\":\"https:\\\/\\\/www.paudimodel.com\\\/wp-content\\\/litespeed\\\/avatar\\\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858\",\"caption\":\"Paudi_Products02\"},\"url\":\"https:\\\/\\\/www.paudimodel.com\\\/en\\\/author\\\/paudi_products02\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car - Paudi Model | High Quality Diecast Model","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.paudimodel.com\/en\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/?wmc-currency=USD","og_locale":"en_US","og_type":"article","og_title":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car","og_url":"https:\/\/www.paudimodel.com\/en\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/?wmc-currency=USD","og_site_name":"Paudi Model | High Quality Diecast Model","article_publisher":"https:\/\/www.facebook\/paudimodel","article_published_time":"2017-04-18T01:42:36+00:00","article_modified_time":"2017-05-01T09:33:00+00:00","og_image":[{"width":990,"height":658,"url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg","type":"image\/jpeg"}],"author":"Paudi_Products02","twitter_card":"summary_large_image","twitter_creator":"@paudimodel","twitter_site":"@paudimodel","twitter_misc":{"Written by":"Paudi_Products02"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#article","isPartOf":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/"},"author":{"name":"Paudi_Products02","@id":"https:\/\/www.paudimodel.com\/#\/schema\/person\/987cc7defc51ab0657b80c639bfd1a4c"},"headline":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car","datePublished":"2017-04-18T01:42:36+00:00","dateModified":"2017-05-01T09:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/"},"wordCount":17,"commentCount":4,"publisher":{"@id":"https:\/\/www.paudimodel.com\/#organization"},"image":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg","keywords":["1 18 model cars","1 18 scale model cars","1:18 die-cast model car","car model","model car","scale model cars","toy"],"articleSection":["Interactive blog"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/","url":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/","name":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car - Paudi Model | High Quality Diecast Model","isPartOf":{"@id":"https:\/\/www.paudimodel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#primaryimage"},"image":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#primaryimage"},"thumbnailUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg","datePublished":"2017-04-18T01:42:36+00:00","dateModified":"2017-05-01T09:33:00+00:00","breadcrumb":{"@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#primaryimage","url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2016\/04\/Skoda_Rapid_2013_white_001-1.jpg","width":990,"height":658},{"@type":"BreadcrumbList","@id":"https:\/\/www.paudimodel.com\/paudi-model-skoda-rapid-2013-118-scale-diecast-model-car\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.paudimodel.com\/"},{"@type":"ListItem","position":2,"name":"Paudi Model Skoda Rapid 2013 1:18 scale diecast model car"}]},{"@type":"WebSite","@id":"https:\/\/www.paudimodel.com\/#website","url":"https:\/\/www.paudimodel.com\/","name":"Paudi Model | High Quality Diecast Model","description":"Shop For Diecast Models From Top-Rated Brands Like Dealer Edition, Paudi, Kyosho, Autoart &amp; More. Low Online Prices. Super-Detailed Models.Find Your Make &amp; Model.Huge Selection. Satisfaction Guaranteed. Types: Diecast Model Cars, Diecast Model Trucks.","publisher":{"@id":"https:\/\/www.paudimodel.com\/#organization"},"alternateName":"Scale model design, development and production","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.paudimodel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.paudimodel.com\/#organization","name":"Guangzhou Paudi Model Technology Ltd.","url":"https:\/\/www.paudimodel.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/uploads\/2023\/02\/696x696.png","width":696,"height":696,"caption":"Guangzhou Paudi Model Technology Ltd."},"image":{"@id":"https:\/\/www.paudimodel.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook\/paudimodel","https:\/\/x.com\/paudimodel"]},{"@type":"Person","@id":"https:\/\/www.paudimodel.com\/#\/schema\/person\/987cc7defc51ab0657b80c639bfd1a4c","name":"Paudi_Products02","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858","url":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858","contentUrl":"https:\/\/www.paudimodel.com\/wp-content\/litespeed\/avatar\/6c52fd4474e293b3de1b0961dd7fa31d.jpg?ver=1778668858","caption":"Paudi_Products02"},"url":"https:\/\/www.paudimodel.com\/en\/author\/paudi_products02\/"}]}},"_links":{"self":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/posts\/47591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/comments?post=47591"}],"version-history":[{"count":0,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/posts\/47591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/media\/42687"}],"wp:attachment":[{"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/media?parent=47591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/categories?post=47591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.paudimodel.com\/en\/wp-json\/wp\/v2\/tags?post=47591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}